{"id":13761,"date":"2024-12-20T10:36:25","date_gmt":"2024-12-20T09:36:25","guid":{"rendered":"https:\/\/www.zsg.ch\/erlebnisschiffe\/heisser-stein-schiff-14052025\/"},"modified":"2025-12-17T09:34:20","modified_gmt":"2025-12-17T08:34:20","slug":"hot-stone-grill-cruise-130526","status":"publish","type":"zsg-erlebnisschiffe","link":"https:\/\/www.zsg.ch\/en\/unique-cruises\/hot-stone-grill-cruise-130526\/","title":{"rendered":"Hot Stone Grill Cruise"},"template":"","class_list":["post-13761","zsg-erlebnisschiffe","type-zsg-erlebnisschiffe","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.zsg.ch\/en\/wp-json\/wp\/v2\/zsg-erlebnisschiffe\/13761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zsg.ch\/en\/wp-json\/wp\/v2\/zsg-erlebnisschiffe"}],"about":[{"href":"https:\/\/www.zsg.ch\/en\/wp-json\/wp\/v2\/types\/zsg-erlebnisschiffe"}],"wp:attachment":[{"href":"https:\/\/www.zsg.ch\/en\/wp-json\/wp\/v2\/media?parent=13761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}